{"id":1271,"date":"2024-10-07T21:11:20","date_gmt":"2024-10-07T21:11:20","guid":{"rendered":"https:\/\/funciondigital.com\/ypf-sa-argentina\/"},"modified":"2024-10-22T18:12:16","modified_gmt":"2024-10-22T18:12:16","slug":"ypf-sa-argentina","status":"publish","type":"post","link":"https:\/\/funciondigital.com\/pt-br\/ypf-sa-argentina\/","title":{"rendered":"YPF SA ARGENTINA"},"content":{"rendered":"\n<h2 class=\"wp-block-heading has-text-color has-link-color wp-elements-1\" style=\"color:#222bf7\"><strong>YPF SA ARGENTINA<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\"><strong>Melhorando a seguran\u00e7a em campos de petr\u00f3leo e escrit\u00f3rios corporativos: nosso trabalho com a YPF S.A.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>A YPF S.A.<\/strong>, empresa l\u00edder no setor de energia na Argentina, confiou \u00e0 <strong>Funci\u00f3n Digital a<\/strong> execu\u00e7\u00e3o de um projeto abrangente de seguran\u00e7a em suas instala\u00e7\u00f5es localizadas em Buenos Aires e Tierra del Fuego. Nosso objetivo era refor\u00e7ar a prote\u00e7\u00e3o em seus campos de petr\u00f3leo, destilarias e escrit\u00f3rios corporativos, implementando solu\u00e7\u00f5es tecnol\u00f3gicas de alta qualidade que atendessem aos mais altos padr\u00f5es de seguran\u00e7a. <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Solu\u00e7\u00f5es de seguran\u00e7a para a YPF S.A.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">O projeto para a <strong>YPF<\/strong> envolveu uma an\u00e1lise completa de suas necessidades de seguran\u00e7a, tanto em ambientes industriais quanto em espa\u00e7os corporativos, o que resultou na instala\u00e7\u00e3o dos seguintes sistemas:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>CCTV (Circuito Fechado de Televis\u00e3o)<\/strong>: implementamos um sistema de c\u00e2meras de vigil\u00e2ncia que cobre \u00e1reas cr\u00edticas em locais e escrit\u00f3rios, fornecendo monitoramento constante e detalhado que garante a seguran\u00e7a das instala\u00e7\u00f5es.<\/li>\n\n\n\n<li><strong>Sistema de intrus\u00e3o de per\u00edmetro<\/strong>: nos campos e destilarias, instalamos um sistema avan\u00e7ado de detec\u00e7\u00e3o de intrus\u00e3o que protege as \u00e1reas do per\u00edmetro, permitindo uma resposta r\u00e1pida a qualquer acesso n\u00e3o autorizado.<\/li>\n\n\n\n<li><strong>Detec\u00e7\u00e3o de inc\u00eandio<\/strong>: para garantir a conformidade com os mais rigorosos padr\u00f5es de seguran\u00e7a industrial, instalamos um sistema de detec\u00e7\u00e3o de inc\u00eandio em todas as \u00e1reas sens\u00edveis, o que permite a tomada de a\u00e7\u00e3o imediata em caso de incidente.<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\"><strong>Impacto nas opera\u00e7\u00f5es da YPF S.A.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Com a implementa\u00e7\u00e3o desses sistemas, <strong>a YPF S.A.<\/strong> refor\u00e7ou significativamente a seguran\u00e7a em seus campos, escrit\u00f3rios e destilarias, garantindo a prote\u00e7\u00e3o de suas opera\u00e7\u00f5es e de seu pessoal.<br\/>Esses sistemas de vigil\u00e2ncia, detec\u00e7\u00e3o e controle s\u00e3o essenciais para garantir a continuidade operacional e minimizar os riscos em um dos setores mais exigentes do pa\u00eds. Na<strong>Funci\u00f3n Digital<\/strong>, temos o compromisso de fornecer solu\u00e7\u00f5es personalizadas para cada um de nossos clientes. Estamos orgulhosos de ter feito parte desse importante projeto, contribuindo para a seguran\u00e7a e o sucesso da <strong>YPF S.A.<\/strong> em suas opera\u00e7\u00f5es estrat\u00e9gicas na Argentina.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>YPF SA ARGENTINA Melhorando a seguran\u00e7a em campos de petr\u00f3leo e escrit\u00f3rios corporativos: nosso trabalho com a YPF S.A. A YPF S.A., empresa l\u00edder no setor de energia na Argentina, confiou \u00e0 Funci\u00f3n Digital a execu\u00e7\u00e3o de um projeto abrangente de seguran\u00e7a em suas instala\u00e7\u00f5es localizadas em Buenos Aires e Tierra del Fuego. Nosso objetivo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1463,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","footnotes":""},"categories":[45],"tags":[],"class_list":["post-1271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-energia-pt-br"],"_links":{"self":[{"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/posts\/1271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/comments?post=1271"}],"version-history":[{"count":2,"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/posts\/1271\/revisions"}],"predecessor-version":[{"id":1275,"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/posts\/1271\/revisions\/1275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/media\/1463"}],"wp:attachment":[{"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/media?parent=1271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/categories?post=1271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/funciondigital.com\/pt-br\/wp-json\/wp\/v2\/tags?post=1271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}